{"id":643,"date":"2018-01-26T20:08:47","date_gmt":"2018-01-26T22:08:47","guid":{"rendered":"http:\/\/www.encontragoiania.com.br\/sobre\/?p=643"},"modified":"2019-04-15T11:52:13","modified_gmt":"2019-04-15T14:52:13","slug":"cafe-de-la-musique-goiania","status":"publish","type":"post","link":"https:\/\/www.encontragoiania.com.br\/sobre\/cafe-de-la-musique-goiania\/","title":{"rendered":"Caf\u00e9 de La Musique Goi\u00e2nia"},"content":{"rendered":"<div class=\"196752fdcd61442359b13893514e4d90\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Sucesso absoluto em cidades como Florian\u00f3polis, Porto Alegre, S\u00e3o Paulo e v\u00e1rias outras, chegou para ser o Dining Music mais charmoso de Goi\u00e2nia! Conhe\u00e7a mais informa\u00e7\u00f5es sobre o <strong>Caf\u00e9 de La Musique Goi\u00e2nia.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-644 size-full\" title=\"Caf\u00e9 de La Musique Goi\u00e2nia\" src=\"http:\/\/www.encontragoiania.com.br\/sobre\/wp-content\/uploads\/2018\/01\/cafe-de-la-musique-goiania.gif\" alt=\"Caf\u00e9 de La Musique Goi\u00e2nia\" width=\"680\" height=\"189\" \/><\/p>\n<h3>Hor\u00e1rio de Funcionamento\u00a0Caf\u00e9 de La Musique em Goi\u00e2nia<\/h3>\n<ul>\n<li>Sexta e S\u00e1bado das 22h \u00e0s 04h<\/li>\n<\/ul>\n<h3>Endere\u00e7o e Telefone\u00a0Caf\u00e9 de La Musique\u00a0em Goi\u00e2nia<\/h3>\n<ul>\n<li>Rua 146, 500 &#8211; Setor Marista &#8211; Goi\u00e2nia &#8211; GO<\/li>\n<li>Telefone: (62) 3922-2353<\/li>\n<\/ul>\n<h3>Outras informa\u00e7\u00f5es e site<\/h3>\n<ul>\n<li>Mais informa\u00e7\u00f5es:\u00a0<a href=\"https:\/\/www.facebook.com\/cafedelamusique\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.facebook.com\/cafedelamusique<\/a><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-625\" src=\"http:\/\/www.encontragoiania.com.br\/sobre\/wp-content\/uploads\/2018\/01\/fechado.png\" alt=\"\" width=\"297\" height=\"52\" \/><\/p>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3821.592868267968!2d-49.262969985133175!3d-16.697244688495555!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x935ef1144f5845c70xcd57bf436deec6d!2sR.+146+500+-+St.+Marista+Goinia+-+GO+74170-090!5e0!3m2!1spt-BR!2sbr!4v1517004091922\"><img decoding=\"async\" src=\"http:\/\/www.encontragoiania.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Sucesso absoluto em cidades como Florian\u00f3polis, Porto Alegre, S\u00e3o Paulo e v\u00e1rias outras, chegou para ser o Dining Music mais charmoso de Goi\u00e2nia! Conhe\u00e7a mais informa\u00e7\u00f5es sobre o Caf\u00e9 de La Musique Goi\u00e2nia. Hor\u00e1rio de Funcionamento\u00a0Caf\u00e9 de La Musique em Goi\u00e2nia Sexta e S\u00e1bado das 22h \u00e0s 04h Endere\u00e7o e Telefone\u00a0Caf\u00e9 de La Musique\u00a0em Goi\u00e2nia Rua 146, 500 &#8211; Setor Marista &#8211; Goi\u00e2nia &#8211; GO Telefone: (62) 3922-2353 Outras informa\u00e7\u00f5es e site Mais informa\u00e7\u00f5es:\u00a0www.facebook.com\/cafedelamusique Mapa de localiza\u00e7\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":644,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-para-beber-goiania","has_thumb"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/posts\/643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=643"}],"version-history":[{"count":0,"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/posts\/643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/media\/644"}],"wp:attachment":[{"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontragoiania.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}